{"id":113492,"date":"2024-11-21T12:56:12","date_gmt":"2024-11-21T11:56:12","guid":{"rendered":"https:\/\/www.flinqproducts.nl\/product\/flinq-rollable-puzzle-mat\/"},"modified":"2026-03-25T14:22:08","modified_gmt":"2026-03-25T13:22:08","slug":"flinq-rollable-puzzle-mat","status":"publish","type":"product","link":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/","title":{"rendered":"FlinQ Roll-up Puzzle Mat"},"content":{"rendered":"<p>Enjoy worry-free puzzle fun with the FlinQ rollable puzzle mat and let all stress disappear. The puzzle mat not only provides a perfect place to lay your puzzle but also takes away any last concerns you might have. Doing a puzzle is a moment of relaxation, and with our mat, this moment becomes even more valuable. The pressure to finish the puzzle disappears because you can easily store it, even if it&#8217;s not yet completed. This way, you quickly make room for other activities, like a cozy dinner at a tidy table.    <\/p>\n<p><strong>The puzzle storage solution <\/strong><br \/>\nThe FlinQ puzzle mat is the ideal storage solution for puzzle enthusiasts, available in two sizes for puzzles up to 1500 or 3000 pieces. Thanks to the non-slip natural rubber underside and the silky polyester top, the mat stays firmly on the table and doesn&#8217;t fray. Your puzzle remains perfectly intact when you roll it up in one smooth motion, without<br \/>\nlosing any pieces.  <\/p>\n<p><strong>Great as a gift!<\/strong><br \/>\nThe puzzle mat is not only a practical solution, but also a thoughtful gift for puzzle fans. A gift for Christmas, birthdays, anniversaries, Mother&#8217;s Day, Father&#8217;s Day, or any occasion where you want to share the joy of puzzling. <\/p>\n<p><strong>Benefits<\/strong><br \/>\n&#8211; Easy to roll up in one motion<br \/>\n&#8211; Space for giant jigsaw puzzles up to 3,000 pieces<br \/>\n&#8211; Non-slip rubber underside<br \/>\n&#8211; Easy to store<br \/>\n&#8211; Puzzle pieces glide effortlessly<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"usps-spp\" style=\"margin-bottom: 20px;\"><i class=\"fa-solid fa-check\" style=\"color: #52b526;\"><\/i> Easy to roll up in one motion<br \/><i class=\"fa-solid fa-check\" style=\"color: #52b526;\"><\/i> Non-slip rubber underside<br \/><i class=\"fa-solid fa-check\" style=\"color: #52b526;\"><\/i> Easy to store<\/div>\n","protected":false},"featured_media":113514,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[463],"product_tag":[],"class_list":{"0":"post-113492","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-travel-leisure","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FlinQ - FlinQ Roll-up Puzzle Mat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FlinQ - FlinQ Roll-up Puzzle Mat\" \/>\n<meta property=\"og:description\" content=\"Easy to roll up in one motion Non-slip rubber underside Easy to store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/\" \/>\n<meta property=\"og:site_name\" content=\"FlinQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FlinqProducts\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T13:22:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/11\/FlinQ-Rollable-Puzzle-Mat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/\",\"url\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/\",\"name\":\"FlinQ - FlinQ Roll-up Puzzle Mat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.flinqproducts.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FlinQ-Rollable-Puzzle-Mat.jpg\",\"datePublished\":\"2024-11-21T11:56:12+00:00\",\"dateModified\":\"2026-03-25T13:22:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.flinqproducts.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FlinQ-Rollable-Puzzle-Mat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.flinqproducts.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FlinQ-Rollable-Puzzle-Mat.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/product\\\/flinq-rollable-puzzle-mat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FlinQ Roll-up Puzzle Mat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/\",\"name\":\"FlinQ\",\"description\":\"Een FlinQ product maakt je leven makkelijker\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#organization\",\"name\":\"FlinQ\",\"url\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.flinqproducts.nl\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/FlinQ-App-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.flinqproducts.nl\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/FlinQ-App-Logo.png\",\"width\":280,\"height\":280,\"caption\":\"FlinQ\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flinqproducts.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FlinqProducts\\\/\",\"https:\\\/\\\/www.instagram.com\\\/flinqproducts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@flinqproducts2240\"],\"email\":\"info@flinqproducts.nl\",\"legalName\":\"FlinQ & Co B.V.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.flinqproducts.nl\\\/klantenservice\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FlinQ - FlinQ Roll-up Puzzle Mat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/","og_locale":"en_US","og_type":"article","og_title":"FlinQ - FlinQ Roll-up Puzzle Mat","og_description":"Easy to roll up in one motion Non-slip rubber underside Easy to store","og_url":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/","og_site_name":"FlinQ","article_publisher":"https:\/\/www.facebook.com\/FlinqProducts\/","article_modified_time":"2026-03-25T13:22:08+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/11\/FlinQ-Rollable-Puzzle-Mat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/","url":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/","name":"FlinQ - FlinQ Roll-up Puzzle Mat","isPartOf":{"@id":"https:\/\/www.flinqproducts.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/#primaryimage"},"image":{"@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/11\/FlinQ-Rollable-Puzzle-Mat.jpg","datePublished":"2024-11-21T11:56:12+00:00","dateModified":"2026-03-25T13:22:08+00:00","breadcrumb":{"@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/#primaryimage","url":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/11\/FlinQ-Rollable-Puzzle-Mat.jpg","contentUrl":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/11\/FlinQ-Rollable-Puzzle-Mat.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.flinqproducts.nl\/en\/product\/flinq-rollable-puzzle-mat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.flinqproducts.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/www.flinqproducts.nl\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"FlinQ Roll-up Puzzle Mat"}]},{"@type":"WebSite","@id":"https:\/\/www.flinqproducts.nl\/en\/#website","url":"https:\/\/www.flinqproducts.nl\/en\/","name":"FlinQ","description":"Een FlinQ product maakt je leven makkelijker","publisher":{"@id":"https:\/\/www.flinqproducts.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flinqproducts.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.flinqproducts.nl\/en\/#organization","name":"FlinQ","url":"https:\/\/www.flinqproducts.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.flinqproducts.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/02\/FlinQ-App-Logo.png","contentUrl":"https:\/\/www.flinqproducts.nl\/wp-content\/uploads\/2024\/02\/FlinQ-App-Logo.png","width":280,"height":280,"caption":"FlinQ"},"image":{"@id":"https:\/\/www.flinqproducts.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FlinqProducts\/","https:\/\/www.instagram.com\/flinqproducts\/","https:\/\/www.youtube.com\/@flinqproducts2240"],"email":"info@flinqproducts.nl","legalName":"FlinQ & Co B.V.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.flinqproducts.nl\/klantenservice\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/product\/113492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/comments?post=113492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/media\/113514"}],"wp:attachment":[{"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/media?parent=113492"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/product_brand?post=113492"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/product_cat?post=113492"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.flinqproducts.nl\/en\/wp-json\/wp\/v2\/product_tag?post=113492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}